{"id":1984,"date":"2021-05-06T16:55:01","date_gmt":"2021-05-06T16:55:01","guid":{"rendered":"http:\/\/www.migtra.com\/blog\/"},"modified":"2021-07-20T14:58:36","modified_gmt":"2021-07-20T14:58:36","slug":"blog","status":"publish","type":"page","link":"https:\/\/www.migtra.com\/en\/blog\/","title":{"rendered":"Blog"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1984\" class=\"elementor elementor-1984 elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ef90c6c elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"4ef90c6c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-25a28734\" data-id=\"25a28734\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-30c69955\" data-id=\"30c69955\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30b9b21c elementor-widget elementor-widget-spacer\" data-id=\"30b9b21c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-653fd16a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"653fd16a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3e20c8e8\" data-id=\"3e20c8e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-369cf860 elementor-widget elementor-widget-heading\" data-id=\"369cf860\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our<br> Blog<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-26bab357 elementor-widget elementor-widget-spacer\" data-id=\"26bab357\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2bcf48c4\" data-id=\"2bcf48c4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36b1609e elementor-widget elementor-widget-image\" data-id=\"36b1609e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1853\" height=\"900\" src=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/blog-fondo-page.png\" class=\"attachment-full size-full wp-image-582\" alt=\"\" srcset=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/blog-fondo-page.png 1853w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/blog-fondo-page-300x146.png 300w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/blog-fondo-page-1024x497.png 1024w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/blog-fondo-page-768x373.png 768w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/blog-fondo-page-1536x746.png 1536w\" sizes=\"auto, (max-width: 1853px) 100vw, 1853px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64188b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64188b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71f3651\" data-id=\"71f3651\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-419250a elementor-widget elementor-widget-spacer\" data-id=\"419250a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a23e657 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a23e657\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-26245ad\" data-id=\"26245ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fd8eccf\" data-id=\"fd8eccf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a1f3e1 elementor-widget elementor-widget-heading\" data-id=\"9a1f3e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Latest News<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3960fb elementor-grid-1 post-blog11 elementor-hidden-tablet elementor-hidden-phone elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"b3960fb\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2818 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-en\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.migtra.com\/en\/te-contamos-sobre-que-trata-el-documento-de-politica-nacional-de-inteligencia-artificial\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02.jpg\" class=\"attachment-full size-full wp-image-2809\" alt=\"\" srcset=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02.jpg 900w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02-300x300.jpg 300w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02-150x150.jpg 150w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.migtra.com\/en\/te-contamos-sobre-que-trata-el-documento-de-politica-nacional-de-inteligencia-artificial\/\" >\n\t\t\t\tWe tell you about the National Policy on Artificial Intelligence\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 de July de 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef6a70e elementor-widget elementor-widget-spacer\" data-id=\"ef6a70e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abc1593 post-blog22 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"abc1593\" data-element_type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers&quot;,&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2818 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-en\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.migtra.com\/en\/te-contamos-sobre-que-trata-el-documento-de-politica-nacional-de-inteligencia-artificial\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02.jpg\" class=\"attachment-full size-full wp-image-2809\" alt=\"\" srcset=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02.jpg 900w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02-300x300.jpg 300w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02-150x150.jpg 150w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/07\/Portada_Blog_Migtra_Julio_02-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.migtra.com\/en\/te-contamos-sobre-que-trata-el-documento-de-politica-nacional-de-inteligencia-artificial\/\" >\n\t\t\t\tWe tell you about the National Policy on Artificial Intelligence\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 de July de 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2008 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-en\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.migtra.com\/en\/sqm-y-transportes-nazar-reciben-premio-raev-flota-mas-segura-de-chile\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/cuadradablog_migtra-28.png\" class=\"attachment-full size-full wp-image-1978\" alt=\"\" srcset=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/cuadradablog_migtra-28.png 900w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/cuadradablog_migtra-28-300x300.png 300w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/cuadradablog_migtra-28-150x150.png 150w, https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/cuadradablog_migtra-28-768x768.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.migtra.com\/en\/sqm-y-transportes-nazar-reciben-premio-raev-flota-mas-segura-de-chile\/\" >\n\t\t\t\tSQM and Transportes Nazar win \u201cRAEV Award: Chile&#8217;s Safest Fleet\u201d\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 de May de 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2010 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-en\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.migtra.com\/en\/bottleneck-que-son-y-como-afectan-a-la-cadena-de-produccion\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/12\/camiones-blog.jpg\" class=\"attachment-full size-full wp-image-1946\" alt=\"\" srcset=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/12\/camiones-blog.jpg 1500w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/12\/camiones-blog-300x200.jpg 300w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/12\/camiones-blog-1024x683.jpg 1024w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/12\/camiones-blog-768x512.jpg 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.migtra.com\/en\/bottleneck-que-son-y-como-afectan-a-la-cadena-de-produccion\/\" >\n\t\t\t\tBottlenecks: what they are and how they affect the chain of production\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 de December de 2020\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2012 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-en\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.migtra.com\/en\/los-peligros-de-los-excesos-de-velocidad-una-realidad-latente\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1499\" height=\"1000\" src=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/11\/peligro-de-los-excesos.jpg\" class=\"attachment-full size-full wp-image-1942\" alt=\"\" srcset=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/11\/peligro-de-los-excesos.jpg 1499w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/11\/peligro-de-los-excesos-300x200.jpg 300w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/11\/peligro-de-los-excesos-1024x683.jpg 1024w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/11\/peligro-de-los-excesos-768x512.jpg 768w\" sizes=\"auto, (max-width: 1499px) 100vw, 1499px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.migtra.com\/en\/los-peligros-de-los-excesos-de-velocidad-una-realidad-latente\/\" >\n\t\t\t\tThe dangers of speeding: a latent reality\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t3 de November de 2020\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2014 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-en\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.migtra.com\/en\/aniversario-migtra-tres-anos-reforzando-nuestro-compromiso-con-la-tecnologia-y-el-transporte\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1283\" src=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/10\/Equipo-Migtra22-blog.jpg\" class=\"attachment-full size-full wp-image-1944\" alt=\"\" srcset=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/10\/Equipo-Migtra22-blog.jpg 1900w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/10\/Equipo-Migtra22-blog-300x203.jpg 300w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/10\/Equipo-Migtra22-blog-1024x691.jpg 1024w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/10\/Equipo-Migtra22-blog-768x519.jpg 768w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/10\/Equipo-Migtra22-blog-1536x1037.jpg 1536w\" sizes=\"auto, (max-width: 1900px) 100vw, 1900px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.migtra.com\/en\/aniversario-migtra-tres-anos-reforzando-nuestro-compromiso-con-la-tecnologia-y-el-transporte\/\" >\n\t\t\t\tMigtra&#8217;s Anniversary: three years reaffirming our commitment to technology and transport\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t2 de October de 2020\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2016 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-en\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.migtra.com\/en\/la-importancia-de-incluir-soluciones-tecnologicas-para-mantener-la-logistica-de-transporte-en-tiempos-de-pandemia\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1310\" height=\"1000\" src=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/09\/25549-blog.jpg\" class=\"attachment-full size-full wp-image-1948\" alt=\"\" srcset=\"https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/09\/25549-blog.jpg 1310w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/09\/25549-blog-300x229.jpg 300w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/09\/25549-blog-1024x782.jpg 1024w, https:\/\/www.migtra.com\/wp-content\/uploads\/2020\/09\/25549-blog-768x586.jpg 768w\" sizes=\"auto, (max-width: 1310px) 100vw, 1310px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.migtra.com\/en\/la-importancia-de-incluir-soluciones-tecnologicas-para-mantener-la-logistica-de-transporte-en-tiempos-de-pandemia\/\" >\n\t\t\t\tThe importance of including technological solutions to keep transport logistics in times of pandemic\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 de September de 2020\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"2\" data-next-page=\"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/pages\/1984\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/pages\/1984\/page\/2\/\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6d888d6\" data-id=\"6d888d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-414d142 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"414d142\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0a4a3e\" data-id=\"f0a4a3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edd974b elementor-widget elementor-widget-spacer\" data-id=\"edd974b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Our Blog Latest News<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-1984","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Blog - Migtra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.migtra.com\/en\/blog\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blog - Migtra\" \/>\n<meta property=\"og:description\" content=\"Our Blog Latest News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.migtra.com\/en\/blog\/\" \/>\n<meta property=\"og:site_name\" content=\"Migtra\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-20T14:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/blog-fondo-page.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.migtra.com\/en\/blog\/\",\"url\":\"https:\/\/www.migtra.com\/en\/blog\/\",\"name\":\"Blog - Migtra\",\"isPartOf\":{\"@id\":\"https:\/\/www.migtra.com\/#website\"},\"datePublished\":\"2021-05-06T16:55:01+00:00\",\"dateModified\":\"2021-07-20T14:58:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.migtra.com\/en\/blog\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.migtra.com\/en\/blog\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.migtra.com\/en\/blog\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.migtra.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.migtra.com\/#website\",\"url\":\"https:\/\/www.migtra.com\/\",\"name\":\"Migtra\",\"description\":\"Expertos en el mercado de la inteligencia del transporte\",\"publisher\":{\"@id\":\"https:\/\/www.migtra.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.migtra.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.migtra.com\/#organization\",\"name\":\"Migtra\",\"url\":\"https:\/\/www.migtra.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.migtra.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/Capa-2.png\",\"contentUrl\":\"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/Capa-2.png\",\"width\":272,\"height\":40,\"caption\":\"Migtra\"},\"image\":{\"@id\":\"https:\/\/www.migtra.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blog - Migtra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.migtra.com\/en\/blog\/","og_locale":"en_US","og_type":"article","og_title":"Blog - Migtra","og_description":"Our Blog Latest News","og_url":"https:\/\/www.migtra.com\/en\/blog\/","og_site_name":"Migtra","article_modified_time":"2021-07-20T14:58:36+00:00","og_image":[{"url":"http:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/blog-fondo-page.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.migtra.com\/en\/blog\/","url":"https:\/\/www.migtra.com\/en\/blog\/","name":"Blog - Migtra","isPartOf":{"@id":"https:\/\/www.migtra.com\/#website"},"datePublished":"2021-05-06T16:55:01+00:00","dateModified":"2021-07-20T14:58:36+00:00","breadcrumb":{"@id":"https:\/\/www.migtra.com\/en\/blog\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.migtra.com\/en\/blog\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.migtra.com\/en\/blog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.migtra.com\/"},{"@type":"ListItem","position":2,"name":"Blog"}]},{"@type":"WebSite","@id":"https:\/\/www.migtra.com\/#website","url":"https:\/\/www.migtra.com\/","name":"Migtra","description":"Expertos en el mercado de la inteligencia del transporte","publisher":{"@id":"https:\/\/www.migtra.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.migtra.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.migtra.com\/#organization","name":"Migtra","url":"https:\/\/www.migtra.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.migtra.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/Capa-2.png","contentUrl":"https:\/\/www.migtra.com\/wp-content\/uploads\/2021\/05\/Capa-2.png","width":272,"height":40,"caption":"Migtra"},"image":{"@id":"https:\/\/www.migtra.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/pages\/1984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/comments?post=1984"}],"version-history":[{"count":7,"href":"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/pages\/1984\/revisions"}],"predecessor-version":[{"id":2744,"href":"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/pages\/1984\/revisions\/2744"}],"wp:attachment":[{"href":"https:\/\/www.migtra.com\/en\/wp-json\/wp\/v2\/media?parent=1984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}